{"id":2308,"date":"2024-07-17T15:54:20","date_gmt":"2024-07-17T13:54:20","guid":{"rendered":"https:\/\/www.balsamicotradizionale.it\/acetaie-aperte-event\/"},"modified":"2024-11-05T19:01:56","modified_gmt":"2024-11-05T18:01:56","slug":"acetaie-aperte-event","status":"publish","type":"page","link":"https:\/\/www.balsamicotradizionale.it\/en\/acetaie-aperte-event\/","title":{"rendered":"Acetaie Aperte event"},"content":{"rendered":"\n<section id=\"introduction\" class=\"introduction\">\n    <div class=\"container\">\n        <div class=\"sezione\">\n            Acetaie Aperte        <\/div>\n            <div class=\"intro-pagina\">\n            <h2> The annual promotional event for food lovers and not only.<\/h2>\n        <\/div>\n        \n                <!-- Immagine (comportamento originale) -->\n        <div class=\"figure-container\">\n            <figure>\n                <img decoding=\"async\" src=\"https:\/\/www.balsamicotradizionale.it\/wp-content\/uploads\/2024\/08\/aceto-balsamico-tradizionale-di-modena-acetaie-aperte-v2.jpg\"\n                    alt=\"aceto balsamico tradizionale di modena -evento acetaie aperte\" \/>\n                <div class=\"border-overlay\"><\/div>\n            <\/figure>\n        <\/div>\n        \n                <div class=\"descrizione-pagina\"><p>Guided tours, tastings, sensory analyses to discover the secrets of Traditional Balsamic Vinegar of Modena P.D.O. and appreciate and identify its characteristics.<\/p><\/div>\n            <\/div>\n<\/section>\n<section id=\"titolo-testo-6a046762da392\" class=\"titolo-testo container   no-padding \">\n\n  \n  <div class=\"titolo-testo__testo\">\n    <p>\u201cAcetaie Aperte\u201d (Open Vinegar Lofts) is a unique opportunity to immerse yourself in the fascinating and history-packed world of Traditional Balsamic Vinegar of Modena P.D.O. This event, <strong>held every year on a Sunday in September<\/strong>, opens the doors of the vinegar lofts to visitors, giving them an amazing chance to discover the production secrets of one of the finest and most beloved products in the world.<\/p>\n<p>The history of Traditional Balsamic Vinegar of Modena goes back centuries: the tradition of producing balsamic vinegar has been passed down from generation to generation, carefully preserving the artisan techniques and secrets that make this product unique.<\/p>\n<p>During &#8220;<strong>Acetaie Aperte<\/strong>&#8220;, visitors can <strong>explore the historic vinegar lofts<\/strong>, many of which are still managed by families that have been making balsamic vinegar for generations. The <strong>guided tours<\/strong> are an opportunity to observe the production process at close quarters, from the careful selection of the grapes to the cooking of the must, from fermentation and ageing in the batteries of wooden barrels, through to bottling. Every step of the process is performed with the utmost care and attention to detail, following the Product Specifications, which guarantee the quality and authenticity of the product, to the letter.<\/p>\n  <\/div>\n\n<\/section>\n<section id=\"gallery-6a046762dc163\" class=\"gallery splide\">\n    <div class=\"splide__track\">\n        <ul class=\"splide__list\">\n                            <li class=\"splide__slide\">\n                    <img decoding=\"async\" src=\"https:\/\/www.balsamicotradizionale.it\/wp-content\/uploads\/2024\/07\/aceto-balsamico-tradizionale-di-modena-acetaie-aperte-ospiti-in-acetaia.jpg\" alt=\"immagine gallery\">\n                <\/li>\n                                <li class=\"splide__slide\">\n                    <img decoding=\"async\" src=\"https:\/\/www.balsamicotradizionale.it\/wp-content\/uploads\/2024\/07\/aceto-balsamico-tradizionale-di-modena-acetaie-aperte-batterie-botti.jpg\" alt=\"immagine gallery\">\n                <\/li>\n                                <li class=\"splide__slide\">\n                    <img decoding=\"async\" src=\"https:\/\/www.balsamicotradizionale.it\/wp-content\/uploads\/2024\/07\/aceto-balsamico-tradizionale-di-modena-acetaie-aperte-lavorazione.jpg\" alt=\"immagine gallery\">\n                <\/li>\n                                <li class=\"splide__slide\">\n                    <img decoding=\"async\" src=\"https:\/\/www.balsamicotradizionale.it\/wp-content\/uploads\/2024\/07\/aceto-balsamico-tradizionale-di-modena-acetaie-aperte-ospiti-in-acetaia-a-tavola.jpg\" alt=\"immagine gallery\">\n                <\/li>\n                                <li class=\"splide__slide\">\n                    <img decoding=\"async\" src=\"https:\/\/www.balsamicotradizionale.it\/wp-content\/uploads\/2024\/07\/aceto-balsamico-tradizionale-di-modena-acetaie-aperte-boccette.jpg\" alt=\"immagine gallery\">\n                <\/li>\n                                <li class=\"splide__slide\">\n                    <img decoding=\"async\" src=\"https:\/\/www.balsamicotradizionale.it\/wp-content\/uploads\/2024\/07\/aceto-balsamico-tradizionale-di-modena-acetaie-aperte-dettaglio-botte.jpg\" alt=\"immagine gallery\">\n                <\/li>\n                        <\/ul>\n    <\/div>\n\n    <script>\n        document.addEventListener('DOMContentLoaded', function () {\n            new Splide('#gallery-6a046762dc163', {\n                type: 'loop',\n                padding: '15rem',\n                gap: '2rem',\n                pagination: false,\n                breakpoints: {\n                    768: {\n                        padding: '5rem',\n                    },\n                }\n            }).mount();\n        });\n    <\/script>\n\n<\/section>\n<section id=\"titolo-testo-6a046762dcf65\" class=\"titolo-testo container   no-padding \">\n\n  \n  <div class=\"titolo-testo__testo\">\n    <p>As well as learning about the production process, the event is also a chance to taste different varieties of Traditional Balsamic Vinegar of Modena P.D.O., including Affinato (aged for a minimum of 12 years) and Extravecchio (aged for a minimum of 25 years). Guided tastings will help participants appreciate the organoleptic characteristics of each type of vinegar, exploring the nuances of flavour, aroma and consistency that make it unique.<\/p>\n<p>The event is also an important opportunity to discover the local area. With its culinary heritage and long tradition of gastronomic excellence, every year Modena attracts thousands of visitors from all over the world. \u201cAcetaie Aperte\u201d helps to consolidate this reputation, guaranteeing visitors an authentic and unforgettable experience.<\/p>\n<p>Taking part in \u201cAcetaie Aperte\u201d not only means discovering an incredible product, it also means supporting a centuries-old tradition and integral part of the cultural and culinary identity of Modena. Don\u2019t miss the chance to enjoy a unique experience, where past and present come together to celebrate excellence.<\/p>\n<p>See the programme at <a href=\"http:\/\/www.acetaieaperte.com\" target=\"_blank\" rel=\"noopener\">www.acetaieaperte.com<\/a><\/p>\n  <\/div>\n\n<\/section>","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":310,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-2308","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Acetaie Aperte event | Traditional Modena Balsamic Vinegar P.D.O.<\/title>\n<meta name=\"description\" content=\"Join Acetaie Aperte and explore Balsamic Vinegar PDO with guided tours, tastings, and fascinating immersive experiences in Modena, Italy.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.balsamicotradizionale.it\/en\/acetaie-aperte-event\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Acetaie Aperte event | Traditional Modena Balsamic Vinegar P.D.O.\" \/>\n<meta property=\"og:description\" content=\"Join Acetaie Aperte and explore Balsamic Vinegar PDO with guided tours, tastings, and fascinating immersive experiences in Modena, Italy.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.balsamicotradizionale.it\/en\/acetaie-aperte-event\/\" \/>\n<meta property=\"og:site_name\" content=\"Consorzio Aceto Balsamico Tradizionale di Modena\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/acetobalsamicotradizionaledop\" \/>\n<meta property=\"article:modified_time\" content=\"2024-11-05T18:01:56+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.balsamicotradizionale.it\/wp-content\/uploads\/2024\/10\/FB-home-sharing-image-aceto-balsamico-tradizionale-di-modena-DOP.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.balsamicotradizionale.it\/en\/acetaie-aperte-event\/\",\"url\":\"https:\/\/www.balsamicotradizionale.it\/en\/acetaie-aperte-event\/\",\"name\":\"Acetaie Aperte event | Traditional Modena Balsamic Vinegar P.D.O.\",\"isPartOf\":{\"@id\":\"https:\/\/www.balsamicotradizionale.it\/en\/#website\"},\"datePublished\":\"2024-07-17T13:54:20+00:00\",\"dateModified\":\"2024-11-05T18:01:56+00:00\",\"description\":\"Join Acetaie Aperte and explore Balsamic Vinegar PDO with guided tours, tastings, and fascinating immersive experiences in Modena, Italy.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.balsamicotradizionale.it\/en\/acetaie-aperte-event\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.balsamicotradizionale.it\/en\/acetaie-aperte-event\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.balsamicotradizionale.it\/en\/acetaie-aperte-event\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.balsamicotradizionale.it\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Acetaie Aperte event\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.balsamicotradizionale.it\/en\/#website\",\"url\":\"https:\/\/www.balsamicotradizionale.it\/en\/\",\"name\":\"Consorzio Aceto Balsamico Tradizionale di Modena DOP\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/www.balsamicotradizionale.it\/en\/#organization\"},\"alternateName\":\"Aceto Balsamico Tradizionale di Modena DOP\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.balsamicotradizionale.it\/en\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.balsamicotradizionale.it\/en\/#organization\",\"name\":\"Consorzio Tutela Aceto Balsamico Tradizionale di Modena\",\"url\":\"https:\/\/www.balsamicotradizionale.it\/en\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.balsamicotradizionale.it\/en\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.balsamicotradizionale.it\/wp-content\/uploads\/2024\/06\/Logo-ABTM-TUTTO-ORO-3-1.png\",\"contentUrl\":\"https:\/\/www.balsamicotradizionale.it\/wp-content\/uploads\/2024\/06\/Logo-ABTM-TUTTO-ORO-3-1.png\",\"width\":160,\"height\":176,\"caption\":\"Consorzio Tutela Aceto Balsamico Tradizionale di Modena\"},\"image\":{\"@id\":\"https:\/\/www.balsamicotradizionale.it\/en\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/acetobalsamicotradizionaledop\",\"https:\/\/www.instagram.com\/balsamicotradizionale\/\",\"https:\/\/www.linkedin.com\/company\/consorzio-aceto-balsamico-tradizionale-modena\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Acetaie Aperte event | Traditional Modena Balsamic Vinegar P.D.O.","description":"Join Acetaie Aperte and explore Balsamic Vinegar PDO with guided tours, tastings, and fascinating immersive experiences in Modena, Italy.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.balsamicotradizionale.it\/en\/acetaie-aperte-event\/","og_locale":"en_US","og_type":"article","og_title":"Acetaie Aperte event | Traditional Modena Balsamic Vinegar P.D.O.","og_description":"Join Acetaie Aperte and explore Balsamic Vinegar PDO with guided tours, tastings, and fascinating immersive experiences in Modena, Italy.","og_url":"https:\/\/www.balsamicotradizionale.it\/en\/acetaie-aperte-event\/","og_site_name":"Consorzio Aceto Balsamico Tradizionale di Modena","article_publisher":"https:\/\/www.facebook.com\/acetobalsamicotradizionaledop","article_modified_time":"2024-11-05T18:01:56+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/www.balsamicotradizionale.it\/wp-content\/uploads\/2024\/10\/FB-home-sharing-image-aceto-balsamico-tradizionale-di-modena-DOP.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.balsamicotradizionale.it\/en\/acetaie-aperte-event\/","url":"https:\/\/www.balsamicotradizionale.it\/en\/acetaie-aperte-event\/","name":"Acetaie Aperte event | Traditional Modena Balsamic Vinegar P.D.O.","isPartOf":{"@id":"https:\/\/www.balsamicotradizionale.it\/en\/#website"},"datePublished":"2024-07-17T13:54:20+00:00","dateModified":"2024-11-05T18:01:56+00:00","description":"Join Acetaie Aperte and explore Balsamic Vinegar PDO with guided tours, tastings, and fascinating immersive experiences in Modena, Italy.","breadcrumb":{"@id":"https:\/\/www.balsamicotradizionale.it\/en\/acetaie-aperte-event\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.balsamicotradizionale.it\/en\/acetaie-aperte-event\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.balsamicotradizionale.it\/en\/acetaie-aperte-event\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.balsamicotradizionale.it\/en\/"},{"@type":"ListItem","position":2,"name":"Acetaie Aperte event"}]},{"@type":"WebSite","@id":"https:\/\/www.balsamicotradizionale.it\/en\/#website","url":"https:\/\/www.balsamicotradizionale.it\/en\/","name":"Consorzio Aceto Balsamico Tradizionale di Modena DOP","description":"","publisher":{"@id":"https:\/\/www.balsamicotradizionale.it\/en\/#organization"},"alternateName":"Aceto Balsamico Tradizionale di Modena DOP","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.balsamicotradizionale.it\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.balsamicotradizionale.it\/en\/#organization","name":"Consorzio Tutela Aceto Balsamico Tradizionale di Modena","url":"https:\/\/www.balsamicotradizionale.it\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.balsamicotradizionale.it\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.balsamicotradizionale.it\/wp-content\/uploads\/2024\/06\/Logo-ABTM-TUTTO-ORO-3-1.png","contentUrl":"https:\/\/www.balsamicotradizionale.it\/wp-content\/uploads\/2024\/06\/Logo-ABTM-TUTTO-ORO-3-1.png","width":160,"height":176,"caption":"Consorzio Tutela Aceto Balsamico Tradizionale di Modena"},"image":{"@id":"https:\/\/www.balsamicotradizionale.it\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/acetobalsamicotradizionaledop","https:\/\/www.instagram.com\/balsamicotradizionale\/","https:\/\/www.linkedin.com\/company\/consorzio-aceto-balsamico-tradizionale-modena"]}]}},"_links":{"self":[{"href":"https:\/\/www.balsamicotradizionale.it\/en\/wp-json\/wp\/v2\/pages\/2308","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.balsamicotradizionale.it\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.balsamicotradizionale.it\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.balsamicotradizionale.it\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.balsamicotradizionale.it\/en\/wp-json\/wp\/v2\/comments?post=2308"}],"version-history":[{"count":2,"href":"https:\/\/www.balsamicotradizionale.it\/en\/wp-json\/wp\/v2\/pages\/2308\/revisions"}],"predecessor-version":[{"id":2552,"href":"https:\/\/www.balsamicotradizionale.it\/en\/wp-json\/wp\/v2\/pages\/2308\/revisions\/2552"}],"wp:attachment":[{"href":"https:\/\/www.balsamicotradizionale.it\/en\/wp-json\/wp\/v2\/media?parent=2308"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}